{"id":1874,"date":"2022-10-30T22:02:20","date_gmt":"2022-10-30T21:02:20","guid":{"rendered":"https:\/\/dev.blz-company.ch\/allgemeine-geschaeftsbedingungen\/"},"modified":"2022-11-29T17:24:37","modified_gmt":"2022-11-29T16:24:37","slug":"allgemeine-geschaeftsbedingungen","status":"publish","type":"page","link":"https:\/\/staging.blz-company.ch\/de\/allgemeine-geschaeftsbedingungen\/","title":{"rendered":"Allgemeine Gesch\u00e4ftsbedingungen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1874\" class=\"elementor elementor-1874 elementor-1241\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0adef8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0adef8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a2b055\" data-id=\"2a2b055\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c6dcd8 elementor-widget elementor-widget-text-editor\" data-id=\"8c6dcd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alle Verk\u00e4ufe sind endg\u00fcltig.<\/p>\n<p>Wir haften f\u00fcr die Produkte, die wir verkaufen. Ihre Zufriedenheit mit Ihrem Kauf ist f\u00fcr uns \u00e4u\u00dferst wichtig. Wenn Sie aus irgendeinem Grund mit Ihrem Kauf nicht zufrieden sind, kontaktieren Sie uns bitte unter info@blz-company.ch.<\/p>\n<p>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Alle Verk\u00e4ufe sind endg\u00fcltig. Wir haften f\u00fcr die Produkte, die wir verkaufen. Ihre Zufriedenheit mit Ihrem Kauf ist f\u00fcr uns \u00e4u\u00dferst wichtig. Wenn Sie aus irgendeinem Grund mit Ihrem Kauf nicht zufrieden sind, kontaktieren Sie uns bitte unter info@blz-company.ch. .<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1874","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allgemeine Gesch\u00e4ftsbedingungen - STAGING blz-company.ch \u2013 Brasserie BLZ-Company<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allgemeine Gesch\u00e4ftsbedingungen - STAGING blz-company.ch \u2013 Brasserie BLZ-Company\" \/>\n<meta property=\"og:description\" content=\"Alle Verk\u00e4ufe sind endg\u00fcltig. Wir haften f\u00fcr die Produkte, die wir verkaufen. Ihre Zufriedenheit mit Ihrem Kauf ist f\u00fcr uns \u00e4u\u00dferst wichtig. Wenn Sie aus irgendeinem Grund mit Ihrem Kauf nicht zufrieden sind, kontaktieren Sie uns bitte unter info@blz-company.ch. .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.blz-company.ch\/de\/allgemeine-geschaeftsbedingungen\/\" \/>\n<meta property=\"og:site_name\" content=\"STAGING blz-company.ch \u2013 Brasserie BLZ-Company\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blzcompany\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-29T16:24:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.blz-company.ch\\\/de\\\/allgemeine-geschaeftsbedingungen\\\/\",\"url\":\"https:\\\/\\\/staging.blz-company.ch\\\/de\\\/allgemeine-geschaeftsbedingungen\\\/\",\"name\":\"Allgemeine Gesch\u00e4ftsbedingungen - STAGING blz-company.ch \u2013 Brasserie BLZ-Company\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.blz-company.ch\\\/#website\"},\"datePublished\":\"2022-10-30T21:02:20+00:00\",\"dateModified\":\"2022-11-29T16:24:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.blz-company.ch\\\/de\\\/allgemeine-geschaeftsbedingungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.blz-company.ch\\\/de\\\/allgemeine-geschaeftsbedingungen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.blz-company.ch\\\/de\\\/allgemeine-geschaeftsbedingungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/staging.blz-company.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allgemeine Gesch\u00e4ftsbedingungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.blz-company.ch\\\/#website\",\"url\":\"https:\\\/\\\/staging.blz-company.ch\\\/\",\"name\":\"STAGING blz-company.ch \u2013 Brasserie BLZ-Company\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.blz-company.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.blz-company.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.blz-company.ch\\\/#organization\",\"name\":\"STAGING blz-company.ch \u2013 Brasserie BLZ-Company\",\"url\":\"https:\\\/\\\/staging.blz-company.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/staging.blz-company.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.blz-company.ch\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-BLZ-LOGO.png\",\"contentUrl\":\"https:\\\/\\\/staging.blz-company.ch\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-BLZ-LOGO.png\",\"width\":1500,\"height\":1295,\"caption\":\"STAGING blz-company.ch \u2013 Brasserie BLZ-Company\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.blz-company.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/blzcompany\",\"https:\\\/\\\/www.instagram.com\\\/blz_company\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allgemeine Gesch\u00e4ftsbedingungen - STAGING blz-company.ch \u2013 Brasserie BLZ-Company","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Allgemeine Gesch\u00e4ftsbedingungen - STAGING blz-company.ch \u2013 Brasserie BLZ-Company","og_description":"Alle Verk\u00e4ufe sind endg\u00fcltig. Wir haften f\u00fcr die Produkte, die wir verkaufen. Ihre Zufriedenheit mit Ihrem Kauf ist f\u00fcr uns \u00e4u\u00dferst wichtig. Wenn Sie aus irgendeinem Grund mit Ihrem Kauf nicht zufrieden sind, kontaktieren Sie uns bitte unter info@blz-company.ch. .","og_url":"https:\/\/staging.blz-company.ch\/de\/allgemeine-geschaeftsbedingungen\/","og_site_name":"STAGING blz-company.ch \u2013 Brasserie BLZ-Company","article_publisher":"https:\/\/www.facebook.com\/blzcompany","article_modified_time":"2022-11-29T16:24:37+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.blz-company.ch\/de\/allgemeine-geschaeftsbedingungen\/","url":"https:\/\/staging.blz-company.ch\/de\/allgemeine-geschaeftsbedingungen\/","name":"Allgemeine Gesch\u00e4ftsbedingungen - STAGING blz-company.ch \u2013 Brasserie BLZ-Company","isPartOf":{"@id":"https:\/\/staging.blz-company.ch\/#website"},"datePublished":"2022-10-30T21:02:20+00:00","dateModified":"2022-11-29T16:24:37+00:00","breadcrumb":{"@id":"https:\/\/staging.blz-company.ch\/de\/allgemeine-geschaeftsbedingungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.blz-company.ch\/de\/allgemeine-geschaeftsbedingungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/staging.blz-company.ch\/de\/allgemeine-geschaeftsbedingungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/staging.blz-company.ch\/"},{"@type":"ListItem","position":2,"name":"Allgemeine Gesch\u00e4ftsbedingungen"}]},{"@type":"WebSite","@id":"https:\/\/staging.blz-company.ch\/#website","url":"https:\/\/staging.blz-company.ch\/","name":"STAGING blz-company.ch \u2013 Brasserie BLZ-Company","description":"","publisher":{"@id":"https:\/\/staging.blz-company.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.blz-company.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/staging.blz-company.ch\/#organization","name":"STAGING blz-company.ch \u2013 Brasserie BLZ-Company","url":"https:\/\/staging.blz-company.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/staging.blz-company.ch\/#\/schema\/logo\/image\/","url":"https:\/\/staging.blz-company.ch\/wp-content\/uploads\/2022\/10\/cropped-BLZ-LOGO.png","contentUrl":"https:\/\/staging.blz-company.ch\/wp-content\/uploads\/2022\/10\/cropped-BLZ-LOGO.png","width":1500,"height":1295,"caption":"STAGING blz-company.ch \u2013 Brasserie BLZ-Company"},"image":{"@id":"https:\/\/staging.blz-company.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blzcompany","https:\/\/www.instagram.com\/blz_company\/"]}]}},"_links":{"self":[{"href":"https:\/\/staging.blz-company.ch\/de\/wp-json\/wp\/v2\/pages\/1874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.blz-company.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.blz-company.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.blz-company.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.blz-company.ch\/de\/wp-json\/wp\/v2\/comments?post=1874"}],"version-history":[{"count":0,"href":"https:\/\/staging.blz-company.ch\/de\/wp-json\/wp\/v2\/pages\/1874\/revisions"}],"wp:attachment":[{"href":"https:\/\/staging.blz-company.ch\/de\/wp-json\/wp\/v2\/media?parent=1874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}